{"id":2682,"date":"2020-01-28T10:49:28","date_gmt":"2020-01-28T12:49:28","guid":{"rendered":"http:\/\/www.colorado.com.br\/nosdacolorado\/?p=2682"},"modified":"2020-01-30T10:56:31","modified_gmt":"2020-01-30T12:56:31","slug":"atencao-estudantes-prioridades-para-as-vagas-nos-onibus","status":"publish","type":"post","link":"https:\/\/www.colorado.com.br\/nosdacolorado\/atencao-estudantes-prioridades-para-as-vagas-nos-onibus\/","title":{"rendered":"Aten\u00e7\u00e3o Estudantes. Prioridades para as vagas nos \u00f4nibus"},"content":{"rendered":"<p><a href=\"http:\/\/www.colorado.com.br\/nosdacolorado\/wp-content\/uploads\/2020\/01\/cartaz-onibus-estudantes.png\" rel=\"prettyPhoto[gallery-JGbf]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2683 size-full\" src=\"http:\/\/www.colorado.com.br\/nosdacolorado\/wp-content\/uploads\/2020\/01\/cartaz-onibus-estudantes.png\" alt=\"\" width=\"596\" height=\"842\" srcset=\"https:\/\/www.colorado.com.br\/nosdacolorado\/wp-content\/uploads\/2020\/01\/cartaz-onibus-estudantes.png 596w, https:\/\/www.colorado.com.br\/nosdacolorado\/wp-content\/uploads\/2020\/01\/cartaz-onibus-estudantes-212x300.png 212w\" sizes=\"auto, (max-width: 596px) 100vw, 596px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":{"0":"post-2682","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-acontece-na-colorado"},"_links":{"self":[{"href":"https:\/\/www.colorado.com.br\/nosdacolorado\/wp-json\/wp\/v2\/posts\/2682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colorado.com.br\/nosdacolorado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.colorado.com.br\/nosdacolorado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.colorado.com.br\/nosdacolorado\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colorado.com.br\/nosdacolorado\/wp-json\/wp\/v2\/comments?post=2682"}],"version-history":[{"count":2,"href":"https:\/\/www.colorado.com.br\/nosdacolorado\/wp-json\/wp\/v2\/posts\/2682\/revisions"}],"predecessor-version":[{"id":2687,"href":"https:\/\/www.colorado.com.br\/nosdacolorado\/wp-json\/wp\/v2\/posts\/2682\/revisions\/2687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colorado.com.br\/nosdacolorado\/wp-json\/wp\/v2\/media\/2684"}],"wp:attachment":[{"href":"https:\/\/www.colorado.com.br\/nosdacolorado\/wp-json\/wp\/v2\/media?parent=2682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.colorado.com.br\/nosdacolorado\/wp-json\/wp\/v2\/categories?post=2682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.colorado.com.br\/nosdacolorado\/wp-json\/wp\/v2\/tags?post=2682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}